{"id":19630,"date":"2023-03-15T23:06:16","date_gmt":"2023-03-15T22:06:16","guid":{"rendered":"https:\/\/www.crystalmc.si\/termini-e-condizioni-generali\/"},"modified":"2025-04-23T13:44:35","modified_gmt":"2025-04-23T11:44:35","slug":"termini-e-condizioni-generali","status":"publish","type":"page","link":"https:\/\/www.crystalmc.si\/it\/termini-e-condizioni-generali\/","title":{"rendered":"Termini e condizioni generali"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19630\" class=\"elementor elementor-19630 elementor-3062\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecf236b elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"ecf236b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9413979\" data-id=\"9413979\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37f0e34 xts-width-100 elementor-widget elementor-widget-xts_title\" data-id=\"37f0e34\" data-element_type=\"widget\" data-widget_type=\"xts_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"xts-section-heading xts-reset-mb-10 xts-reset-last xts-textalign-left\" data-animation-delay=\"\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"xts-section-title title xts-design-default xts-fontsize-l\">\n\t\t\t\t\t\t<span class=\"xts-section-title-text\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\tCONDIZIONI GENERALI DI UTILIZZO DEL SITO WEB\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"xts-section-desc xts-textcolor-custom\">\n\t\t\t\t\t\t<div class=\"xts-section-desc-text xts-reset-all-last\" data-elementor-setting-key=\"description\">\n\t\t\t\t\t\t\t<p>Centro medico Crystal<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42d0b7c elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"42d0b7c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a33eea\" data-id=\"7a33eea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01a194c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"01a194c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67708a56 elementor-section-boxed elementor-section-height-default elementor-section-height-default xts-section-disabled\" data-id=\"67708a56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6848cd70\" data-id=\"6848cd70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5052d21 xts-scheme-inherit xts-textalign-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5052d21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>Crystal Medical Centre, Parmova ulica 53, PE: \u0160tukljeva 46, 1000 Ljubljana, codice fiscale: 94885974, numero di registrazione: 9210652000 \u00e8 responsabile della gestione del sito web www.crystalmc.si ed \u00e8 anche il fornitore di servizi di e-commerce.<\/p>\n<p>Le Condizioni Generali d&#8217;Uso descrivono il funzionamento del sito web, stabiliscono i diritti e gli obblighi dell&#8217;utente dei contenuti e dei servizi del sito web e regolano il rapporto commerciale tra il Centro Medico Crystal e l&#8217;utente. L&#8217;utente del sito web \u00e8 vincolato dalle presenti Condizioni generali d&#8217;uso, pubblicate e accessibili a tutti gli utenti e visitatori del sito web di MC Crystal. <\/p>\n<ol>\n<li>\n<h4><strong>  Descrizione del contenuto del sito web<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>Il sito web di MC Crystal offre i seguenti contenuti :<\/p>\n<p>Informazioni su: servizi sanitari, servizi estetici, servizi medici e cosmetici e altri servizi forniti dall&#8217;azienda. Vengono inoltre fornite informazioni generali per l&#8217;ordinazione, l&#8217;accesso ai servizi e i contatti. <\/p>\n<ol start=\"2\">\n<li>\n<h4><strong>  Tipi di utenti<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>I visitatori del sito web di MC Crystal che sfogliano i contenuti hanno lo status di ospite. Con questo status, pu\u00f2 sfogliare tutti i contenuti informativi del sito e fare una richiesta di servizi. <\/p>\n<ol start=\"3\">\n<li>\n<h4><strong>  Protezione dei dati personali<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>MC Crystal si impegna a proteggere in modo permanente tutti i dati personali dei propri utenti in conformit\u00e0 alla legge sulla protezione dei dati personali, al regolamento generale sulla protezione dei dati dell&#8217;UE e ad altre leggi e regolamenti che disciplinano la protezione dei dati personali.<\/p>\n<ol start=\"4\">\n<li>\n<h4><strong>  Limitazione di responsabilit\u00e0<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>MC Crystal si impegna a fornire informazioni il pi\u00f9 possibile accurate, facili da capire e di alta qualit\u00e0 sul sito web.<\/p>\n<p>Tutti i contenuti pubblicati sono a scopo puramente informativo, MC Crystal non si assume alcuna responsabilit\u00e0 per l&#8217;accuratezza o eventuali errori nelle informazioni pubblicate.<\/p>\n<p>Lo scopo principale \u00e8 quello di informare il pubblico sui servizi forniti da MC Crystal, di educarlo, di semplificare le procedure di appalto e di garantire una comunicazione efficace tra le persone interessate e MC Crystal.<\/p>\n<p>In caso di errori nel testo, ambiguit\u00e0 o fraintendimenti da parte dell&#8217;utente, MC Crystal non sar\u00e0 responsabile per eventuali responsabilit\u00e0 penali o civili nel caso in cui l&#8217;individuo abbia ricevuto una diagnosi o una terapia errata sulla base di tali informazioni errate. I consigli forniti sul sito web non fanno parte del processo di trattamento e dei servizi forniti da MC Crystal.   <\/p>\n<ol start=\"5\">\n<li>\n<h4><strong>  Ordini<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>I pazienti possono fissare un appuntamento per tutti i servizi forniti da Crystal d.o.o. chiamando il numero 01\/ 235 50 20 e durante l&#8217;orario di lavoro presso il Centro Medico Crystal in \u0160tukljeva 46, Lubiana, oppure via e-mail all&#8217;indirizzo info@crystal-mc.si.<\/p>\n<ol start=\"6\">\n<li>\n<h4><strong>  Familiarizzazione con le procedure di trattamento e ottenimento del consenso del paziente per l&#8217;intervento chirurgico<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>Secondo la legge sui diritti del malato, ogni paziente \u00e8 informato di quanto segue al momento della visita da parte del medico in caso di intervento proposto:<\/p>\n<p>&#8211; con il suo stato di salute,<\/p>\n<p>&#8211; lo scopo, il tipo, il metodo, la probabilit\u00e0 di successo e i benefici attesi, l&#8217;esito, i rischi, le conseguenze negative e altri inconvenienti dell&#8217;intervento o della terapia,<\/p>\n<p>&#8211; effetti collaterali o altri possibili inconvenienti<\/p>\n<p>Il paziente viene informato di tutto ci\u00f2 prima dell&#8217;esecuzione della procedura o del servizio, quando riceve anche una copia del modulo di consenso scritto. Senza il consenso scritto del paziente\/cliente, la procedura\/terapia non pu\u00f2 essere eseguita. <\/p>\n<ol start=\"7\">\n<li>\n<h4><strong>  Il diritto di MC Crystal di rifiutare e successivamente di ritirarsi dall&#8217;operazione.<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>Ogni paziente o cliente viene visitato da uno specialista di MC Crystal prima di organizzare un intervento estetico o dermatologico. Sulla base della visita, del colloquio con il paziente e tenendo conto di altri documenti medici pertinenti forniti dal paziente, il medico esprime un parere sull&#8217;idoneit\u00e0 del paziente all&#8217;intervento. Al momento della visita, il medico pu\u00f2 esprimere il parere che il paziente non \u00e8 idoneo ad alcuna procedura, che il paziente \u00e8 idoneo in modo condizionato, il che significa che al momento della visita non sono state soddisfatte tutte le condizioni per l&#8217;esecuzione sicura della procedura e che esiste la possibilit\u00e0 che tali condizioni cambino nel tempo, oppure che il paziente \u00e8 idoneo alla procedura. Se, a seguito dell&#8217;esame, la persona non sceglie di sottoporsi alla procedura presso MC Crystal, MC Crystal non \u00e8 tenuta a rimborsare al paziente il costo della consultazione.   <\/p>\n<p>Il medico del MC Crystal che eseguir\u00e0 l&#8217;intervento ha il diritto, in qualsiasi momento, per motivi che <span style=\"font-size: 16px;\">a suo giudizio aumentano il rischio e riducono la sicurezza e\/o l&#8217;efficacia dell&#8217;intervento, <\/span> di  <span style=\"font-size: 16px;\">si ritira dall&#8217;esecuzione dell&#8217;intervento. Nel caso di motivi legati alle condizioni attuali del paziente, come ad esempio   <\/span><span style=\"font-size: 16px;\">di natura transitoria (guarigione da una condizione di comorbilit\u00e0, altra malattia, gravidanza) il medico o il terapeuta possono suggerire una nuova data per l&#8217;intervento o informare il paziente che l&#8217;intervento sar\u00e0 effettuato in un secondo momento. <\/span><span style=\"font-size: 16px;\">o il terapeuta pu\u00f2 suggerire una nuova data per la procedura o informare il paziente che la procedura sar\u00e0 <\/span><span style=\"font-size: 16px;\">ricevere una nuova data per l&#8217;intervento programmato in un secondo momento, una volta superate le ragioni dell&#8217;attuale inidoneit\u00e0 all&#8217;intervento. <\/span><span style=\"font-size: 16px;\">l&#8217;intervento.<\/span><\/p>\n<p>Nel caso di un motivo permanente successivamente identificato di non idoneit\u00e0 alla procedura, il medico ne spiegher\u00e0 i motivi al paziente.<\/p>\n<ol start=\"8\">\n<li>\n<h4><strong>  Compiti del paziente<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>Al fine di ottenere una procedura di alta qualit\u00e0 e sicura, il paziente \u00e8 tenuto a:<\/p>\n<ul>\n<li>svolgere un ruolo nella protezione, nella promozione e nel ripristino della propria salute<\/li>\n<li>seguire le istruzioni ricevute dagli esperti<\/li>\n<li>fornire al medico competente o al fornitore di cure tutte le informazioni necessarie e veritiere relative al <span style=\"font-size: 16px;\">proprio stato di salute, di cui \u00e8 a conoscenza e che sono rilevanti per le cure successive, in particolare informazioni sulle <\/span><span style=\"font-size: 16px;\">lesioni e le malattie attuali e passate e sul loro trattamento, sugli interventi precedenti, sull&#8217;<\/span><span style=\"font-size: 16px;\">anamnesi familiare di malattie, su eventuali allergie e sui farmaci che sta assumendo, e informare gli operatori sanitari sui <\/span><span style=\"font-size: 16px;\">cambiamenti improvvisi del proprio stato di salute che si verificano durante il trattamento;<\/span><\/li>\n<li>essere attenti e rispettosi della privacy e degli altri diritti degli altri pazienti e degli operatori sanitari;<\/li>\n<li>rispettare gli orari, le regole interne e le procedure organizzative pubblicate dagli operatori <span style=\"font-size: 16px;\">sanitari;<\/span><\/li>\n<li>informare il personale sulla possibilit\u00e0 di guarire da <span style=\"font-size: 16px;\">una malattia infettiva<\/span>, in conformit\u00e0 con le norme interne sulla prevenzione delle infezioni;<\/li>\n<li>rispettare gli standard di igiene delle mani;<\/li>\n<li>I minori di 15 anni devono essere accompagnati dai genitori o da chi ne fa le veci.<\/li>\n<\/ul>\n<ol start=\"9\">\n<li>\n<h4><strong>  Opzioni di pagamento<\/strong><\/h4>\n<\/li>\n<\/ol>\n<ul>\n<li>Offriamo una serie di metodi di pagamento diversi per i servizi:<\/li>\n<li>pagamento in contanti nel luogo del servizio,<\/li>\n<li>pagamento con carta di credito presso la sede del servizio,<\/li>\n<li>pagamento anticipato,<\/li>\n<li>pagamento rateale con carta di credito o di debito presso la sede del servizio.<\/li>\n<\/ul>\n<p>1. Pagamento in contanti presso il luogo di prestazione del servizio<\/p>\n<p>L&#8217;ordine viene effettuato online e il servizio viene pagato in contanti sul posto.<\/p>\n<p>2. Pagamento anticipato<\/p>\n<p>\u00c8 possibile pagare la merce ordinata presso la propria banca o banca online, effettuando un bonifico sul conto di transazione di Crystal d.o.o.. Il pagamento viene effettuato sulla base della fattura ricevuta dopo l&#8217;ordine.<\/p>\n<p>3. Pagamento con carta di credito o di debito presso la sede del servizio.<\/p>\n<p>Potete pagare in modo sicuro la merce ordinata con una carta di credito o di debito (MasterCard, Diners, Visa, Visa <\/p>\n<p>Electron, Maestro) dopo il servizio presso la sede del servizio. Il pagatore deve essere la stessa persona o organizzazione che possiede la carta di credito. Nel caso in cui il titolare della carta non sia cittadino sloveno o utilizzi una carta di credito non emessa in Slovenia e nel caso in cui il beneficiario e l&#8217;ordinante non siano la stessa persona, ci riserviamo il diritto di verificare ulteriormente l&#8217;identit\u00e0 dell&#8217;ordinante e di ricevere una dichiarazione scritta via e-mail che attesti che l&#8217;ordinante \u00e8 d&#8217;accordo con il pagamento del servizio.  <\/p>\n<p>4. Pagamento con carta di credito o di debito presso la sede del servizio.<\/p>\n<p>Il numero di rate dipende dall&#8217;importo della fattura del servizio. La rata minima \u00e8 di 100 euro. <\/p>\n<ol start=\"10\">\n<li>\n<h4><strong>  Reclami e controversie<\/strong><\/h4>\n<\/li>\n<\/ol>\n<p>Il Centro Medico Crystal si impegna a fornire tutti i servizi medici in modo professionale, secondo le regole della professione medica e in conformit\u00e0 con la legislazione vigente. In linea con queste linee guida, l&#8217;azienda si impegna anche a garantire un sistema efficiente per la gestione dei reclami. <\/p>\n<p>In caso di problemi o reclami, gli utenti del sito web MC Crystal possono presentare un reclamo durante gli orari di apertura chiamando il numero 01\/ 235 50 20 o inviando un&#8217;e-mail all&#8217;indirizzo info@crystalmc.si. La procedura di reclamo \u00e8 riservata. Il termine per la presentazione di un reclamo \u00e8 di 30 giorni dall&#8217;erogazione del servizio.  <\/p>\n<p>Poich\u00e9 ci impegniamo per la soddisfazione dei clienti, teniamo conto anche delle opinioni e dei reclami di coloro che hanno gi\u00e0 usufruito dei nostri servizi e risolviamo eventuali controversie in modo amichevole.<\/p>\n<p>Ogni paziente che riceve un servizio sanitario presso il MC Crystal ha diritto a tutti i diritti previsti dalla Legge sui diritti del paziente &#8211; ZPacP.<\/p>\n<p>I pazienti che ritengono che i loro diritti siano stati violati hanno la possibilit\u00e0 di presentare un reclamo scritto o verbale al responsabile dei reclami del MC Crystal. Nell&#8217;esercizio dei propri diritti, il paziente \u00e8 consigliato, assistito o rappresentato da un rappresentante dei diritti del paziente. I recapiti dei rappresentanti dei diritti dei pazienti per localit\u00e0 sono disponibili sul sito web del Ministero della Salute.  <\/p>\n<p>Le presenti Condizioni generali di utilizzo sono valide a partire dalla data di pubblicazione sul sito web. Ci riserviamo il diritto di modificare le presenti Condizioni d&#8217;uso senza preavviso agli utenti. <\/p>\n<p>  L&#8217;uso continuato del sito web di Mc Crystal dopo tale notifica costituisce l&#8217;accettazione dei Termini e condizioni d&#8217;uso. Vi consigliamo di rivedere regolarmente i Termini e le Condizioni d&#8217;uso e di essere a conoscenza di eventuali modifiche. <\/p>\n<p>Crystal, centro medico, d.o.o.<\/p>\n<p>Lubiana, 15.3.2023<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CONDIZIONI GENERALI DI UTILIZZO DEL SITO WEB Centro medico Crystal Crystal Medical Centre, Parmova ulica 53, PE: \u0160tukljeva 46, 1000 Ljubljana, codice fiscale: 94885974, numero di registrazione: 9210652000 \u00e8 responsabile della gestione del sito web www.crystalmc.si ed \u00e8 anche il fornitore di servizi di e-commerce. Le Condizioni Generali d&#8217;Uso descrivono il funzionamento del sito web, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19630","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"www.crystalmc.si","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"termini-e-condizioni-generali","permalinkFormat":"https:\/\/www.crystalmc.si\/it\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/www.crystalmc.si\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"Condizioni generali di utilizzo del sito web","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"aljosa","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/www.crystalmc.si\/it\/","objectID":19630,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/www.crystalmc.si\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/crysta17\/domains\/crystalmc.si\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/www.crystalmc.si\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/crysta17\/domains\/crystalmc.si\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/www.crystalmc.si\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":true,"autoSuggestKeywords":true,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fwww.crystalmc.si%2Fit%2F&r=https%3A%2F%2Fwww.crystalmc.si%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F19630%3Fnonce%3D4c83cd2ebc&pro=1","maxTags":100,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/www.crystalmc.si\/wp-content\/uploads\/2023\/01\/cropped-CrystalMC-favicon-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":true,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/www.crystalmc.si\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Casa","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/pages\/19630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/comments?post=19630"}],"version-history":[{"count":3,"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/pages\/19630\/revisions"}],"predecessor-version":[{"id":19635,"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/pages\/19630\/revisions\/19635"}],"wp:attachment":[{"href":"https:\/\/www.crystalmc.si\/it\/wp-json\/wp\/v2\/media?parent=19630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}